{"id":34,"count":0,"description":"","link":"https:\/\/sid24035.webcdn1.jcloud.no\/index.php\/product-category\/vases\/stygge-vaser\/","name":"Stygge vaser","slug":"stygge-vaser","taxonomy":"product_cat","parent":25,"meta":[],"_links":{"self":[{"href":"https:\/\/sid24035.webcdn1.jcloud.no\/index.php\/wp-json\/wp\/v2\/product_cat\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sid24035.webcdn1.jcloud.no\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sid24035.webcdn1.jcloud.no\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sid24035.webcdn1.jcloud.no\/index.php\/wp-json\/wp\/v2\/product_cat\/25"}],"wp:post_type":[{"href":"https:\/\/sid24035.webcdn1.jcloud.no\/index.php\/wp-json\/wp\/v2\/product?product_cat=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}